{"id":13,"date":"2025-03-28T12:52:18","date_gmt":"2025-03-28T11:52:18","guid":{"rendered":"https:\/\/clinicabenissa.com\/?page_id=13"},"modified":"2026-01-28T19:56:25","modified_gmt":"2026-01-28T18:56:25","slug":"inicio","status":"publish","type":"page","link":"https:\/\/clinicabenissa.com\/de\/","title":{"rendered":"Startseite"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"13\" class=\"elementor elementor-13\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-017d22f e-flex e-con-boxed e-con e-parent\" data-id=\"017d22f\" data-element_type=\"container\" data-e-type=\"container\" id=\"cabecera\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=LvjrnxaLqoE&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;,&quot;background_privacy_mode&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t<\/div>\t\t<div class=\"elementor-element elementor-element-cecc4be elementor-widget elementor-widget-heading\" data-id=\"cecc4be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Wir k\u00fcmmern uns um Sie und Ihre Gesundheit<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-155e69e elementor-widget elementor-widget-text-editor\" data-id=\"155e69e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Cl\u00ednica Benissa bietet eine umfassende medizinische Versorgung mit einem engen und pers\u00f6nlichen Ansatz. Wir haben <strong>Familienmedizin, Zahnmedizin<\/strong> mit verschiedenen Fachrichtungen, <strong>Physiotherapie, Psychologie<\/strong> und <strong>Podiatrie<\/strong>. Wir verf\u00fcgen \u00fcber moderne, hochmoderne Einrichtungen und Ger\u00e4te.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f69eb60 espsup e-flex e-con-boxed e-con e-parent\" data-id=\"f69eb60\" data-element_type=\"container\" data-e-type=\"container\" id=\"tratamientos\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdefd5a elementor-widget elementor-widget-heading\" data-id=\"fdefd5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Behandlungen<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8dcd80f e-grid e-con-full e-con e-child\" data-id=\"8dcd80f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-cc8f674 e-con-full col e-flex e-con e-child\" data-id=\"cc8f674\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/clinicabenissa.com\/de\/allgemeinmedizin\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7031286 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7031286\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Familienmedizin<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-9a500f4 e-con-full col e-flex e-con e-child\" data-id=\"9a500f4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/clinicabenissa.com\/de\/zahnmedizin\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bd9c94 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9bd9c94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Zahnmedizin<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-35de35a e-con-full col e-flex e-con e-child\" data-id=\"35de35a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/clinicabenissa.com\/de\/physiotherapie\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec21db4 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ec21db4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Physiotherapie<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-4482ae7 e-con-full col e-flex e-con e-child\" data-id=\"4482ae7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/clinicabenissa.com\/de\/psychologie\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae5a8cf elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ae5a8cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Psychologie<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-1f637bb e-con-full col e-flex e-con e-child\" data-id=\"1f637bb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/clinicabenissa.com\/de\/podologie\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cb4467 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5cb4467\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Podologie<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-734e313 e-con-full col e-flex e-con e-child\" data-id=\"734e313\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/clinicabenissa.com\/de\/audiologie\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bccd791 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"bccd791\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">H\u00f6rger\u00e4te-Akustikerin<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d69d0f espsup elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"9d69d0f\" data-element_type=\"container\" data-e-type=\"container\" id=\"diagnosticos\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42d3721 elementor-widget elementor-widget-heading\" data-id=\"42d3721\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lernen Sie unsere Diagnostik kennen<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ae7790 e-grid e-con-full e-con e-child\" data-id=\"8ae7790\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2588f71 c1 e-flex e-con-boxed e-con e-child\" data-id=\"2588f71\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21d83d1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"21d83d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb125b4 elementor-widget elementor-widget-text-editor\" data-id=\"fb125b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Elektrokardiogramme<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13ae1d2 c2 e-flex e-con-boxed e-con e-child\" data-id=\"13ae1d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-910a11f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"910a11f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ad3d9f elementor-widget elementor-widget-text-editor\" data-id=\"7ad3d9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Audiometrie<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e84c2f c3 e-flex e-con-boxed e-con e-child\" data-id=\"6e84c2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-470ffbc elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"470ffbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a040cc elementor-widget elementor-widget-text-editor\" data-id=\"4a040cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Pulmonale Funktion<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a class=\"elementor-element elementor-element-d814189 c4 e-flex e-con-boxed e-con e-child\" data-id=\"d814189\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/clinicabenissa.com\/de\/labor\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1b9506 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d1b9506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc80776 elementor-widget elementor-widget-text-editor\" data-id=\"bc80776\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Labor<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1230c9 espsup e-flex e-con-boxed e-con e-parent\" data-id=\"f1230c9\" data-element_type=\"container\" data-e-type=\"container\" id=\"idioma\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-34d4e66 e-con-full col1 e-flex e-con e-child\" data-id=\"34d4e66\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-625acc4 subtitulo elementor-widget elementor-widget-text-editor\" data-id=\"625acc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>BENISSA-KLINIK<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-152db5d elementor-widget elementor-widget-heading\" data-id=\"152db5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir sprechen Ihre Sprache<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20d5ee2 elementor-widget elementor-widget-text-editor\" data-id=\"20d5ee2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wir wissen, wie wichtig es ist, sich verstanden zu f\u00fchlen, wenn es um die eigene Gesundheit geht. <strong>Unser internationales Team zeichnet sich durch eine enge und professionelle medizinische Betreuung aus.<\/strong> Bei Cl\u00ednica Benissa sprechen wir Spanisch, Niederl\u00e4ndisch, Englisch, Deutsch und Franz\u00f6sisch, so dass Sie selbstbewusst und klar kommunizieren k\u00f6nnen - ohne Sprachbarrieren. Wir sind f\u00fcr Sie da, ganz gleich, ob Sie in der Region leben oder nur auf der Durchreise sind. <strong>Denn wenn man weit weg von zu Hause ist, macht es einen gro\u00dfen Unterschied, ob man versteht oder verstanden wird.<\/strong><\/p><p>Wir verf\u00fcgen \u00fcber alle notwendigen diagnostischen Dienstleistungen in der Prim\u00e4rversorgung. Unsere Dental Unit bietet einen umfassenden Service in den Bereichen allgemeine Zahnheilkunde, Kieferorthop\u00e4die, Prothetik, \u00c4sthetik, Chirurgie, Implantate, Parodontologie, Kaumuskelprobleme und Notf\u00e4lle. Die Dental Unit ist mit modernster Technik ausgestattet, um Sie unter optimalen Bedingungen und nat\u00fcrlich in einer entspannten und f\u00fcrsorglichen Atmosph\u00e4re behandeln zu k\u00f6nnen, wie Sie es von unserer Klinik gewohnt sind.\u00a0<\/p><p><strong>Das Zentrum zeichnet sich durch eine enge Zusammenarbeit zwischen Fachleuten in einer freundlichen Atmosph\u00e4re aus. Wir arbeiten mit allen Gesundheitsdiensten in der Region unabh\u00e4ngig und aufmerksam zusammen. Alle Mitarbeiterinnen und Mitarbeiter erf\u00fcllen die Anforderungen der EWG.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d159e4 e-con-full e-flex e-con e-child\" data-id=\"3d159e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dcfb266 elementor-widget elementor-widget-image\" data-id=\"dcfb266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/clinicabenissa.com\/de\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"50\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/10\/Clinica-Benissa-Espanol.png\" class=\"attachment-large size-large wp-image-8245\" alt=\"Clinica Benissa - Englisch\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4409c1a elementor-widget elementor-widget-image\" data-id=\"4409c1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/clinicabenissa.com\/en\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"50\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/10\/Clinica-Benissa-Ingles.png\" class=\"attachment-large size-large wp-image-8249\" alt=\"Clinica Benissa - Ingles\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79f235f elementor-widget elementor-widget-image\" data-id=\"79f235f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/clinicabenissa.com\/nl\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"50\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/10\/Clinica-Benissa-Holandes.png\" class=\"attachment-large size-large wp-image-8248\" alt=\"Clinica Benissa - Niederl\u00e4ndisch\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-685f7b6 elementor-widget elementor-widget-image\" data-id=\"685f7b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/clinicabenissa.com\/de\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/10\/Clinica-Benissa-Aleman.png\" class=\"attachment-large size-large wp-image-8244\" alt=\"Clinica Benissa - Deutsch\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53f79f1 elementor-widget elementor-widget-image\" data-id=\"53f79f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/clinicabenissa.com\/fr\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/10\/Clinica-Benissa-Frances.png\" class=\"attachment-large size-large wp-image-8246\" alt=\"Clinica Benissa - Franz\u00f6sisch\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b27ad18 e-con-full col2 e-flex e-con e-child\" data-id=\"b27ad18\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-104555c elementor-widget elementor-widget-image\" data-id=\"104555c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Entrada-768x1024.jpg\" class=\"attachment-large size-large wp-image-7933\" alt=\"Clinica Benissa - Eingang\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Entrada-768x1024.jpg 768w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Entrada-225x300.jpg 225w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Entrada.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c19198 espsup e-flex e-con-boxed e-con e-parent\" data-id=\"4c19198\" data-element_type=\"container\" data-e-type=\"container\" id=\"equipo\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af558a4 elementor-widget elementor-widget-heading\" data-id=\"af558a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unser Team<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-623860b e-grid e-con-full e-con e-child\" data-id=\"623860b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-0f68269 e-con-full col e-flex e-con e-child\" data-id=\"0f68269\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/clinicabenissa.com\/de\/allgemeinmedizin\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc87c2e elementor-widget elementor-widget-image\" data-id=\"fc87c2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dr.-Max-Meertens-300x300.jpg\" class=\"attachment-medium size-medium wp-image-7804\" alt=\"Clinica Benissa - Dr. Max Meertens\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dr.-Max-Meertens-300x300.jpg 300w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dr.-Max-Meertens-150x150.jpg 150w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dr.-Max-Meertens.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-190b000 elementor-widget elementor-widget-heading\" data-id=\"190b000\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dr. Max Meertens<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6e4be4 elementor-widget elementor-widget-heading\" data-id=\"d6e4be4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Hausarzt<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-6687f2d e-con-full col e-flex e-con e-child\" data-id=\"6687f2d\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/clinicabenissa.com\/de\/zahnmedizin\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4ef804 elementor-widget elementor-widget-image\" data-id=\"a4ef804\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dra.-Alexandra-Rodriguez-300x300.jpg\" class=\"attachment-medium size-medium wp-image-7764\" alt=\"Clinica Benissa - Dr. Alexandra Rodriguez\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dra.-Alexandra-Rodriguez-300x300.jpg 300w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dra.-Alexandra-Rodriguez-150x150.jpg 150w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dra.-Alexandra-Rodriguez.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4f3570 elementor-widget elementor-widget-heading\" data-id=\"e4f3570\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dr. Alexandra Rodr\u00edguez<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88b264d elementor-widget elementor-widget-heading\" data-id=\"88b264d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span style=\"background-color: transparent\">Allgemeine Zahnmedizin, oder<\/span>rthodontie und Implantologie<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-c7c6a4e e-con-full col e-flex e-con e-child\" data-id=\"c7c6a4e\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/clinicabenissa.com\/de\/zahnmedizin\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a4e8d4 elementor-widget elementor-widget-image\" data-id=\"8a4e8d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"300\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/eva-vetter-e1762619756836-256x300.jpeg\" class=\"attachment-medium size-medium wp-image-8721\" alt=\"\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/eva-vetter-e1762619756836-256x300.jpeg 256w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/eva-vetter-e1762619756836-872x1024.jpeg 872w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/eva-vetter-e1762619756836-768x902.jpeg 768w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/eva-vetter-e1762619756836-10x12.jpeg 10w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/eva-vetter-e1762619756836.jpeg 1005w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-883d243 elementor-widget elementor-widget-heading\" data-id=\"883d243\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dr. Eva Vetter<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c784743 elementor-widget elementor-widget-heading\" data-id=\"c784743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Allgemeine Zahnmedizin und Implantologie<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-bb521e2 e-con-full col e-flex e-con e-child\" data-id=\"bb521e2\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/clinicabenissa.com\/de\/zahnmedizin\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9548aaa elementor-widget elementor-widget-image\" data-id=\"9548aaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dra.-Adriana-Voeffray-300x300.jpg\" class=\"attachment-medium size-medium wp-image-7755\" alt=\"Clinica Benissa - Dr. Adriana Voeffray\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dra.-Adriana-Voeffray-300x300.jpg 300w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dra.-Adriana-Voeffray-150x150.jpg 150w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dra.-Adriana-Voeffray.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-876c660 elementor-widget elementor-widget-heading\" data-id=\"876c660\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dr. Adriana Voeffray<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5588fdd elementor-widget elementor-widget-heading\" data-id=\"5588fdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Allgemeine Zahnheilkunde, Kieferorthop\u00e4die und Kinderzahnheilkunde<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-a3fb15f e-con-full col e-flex e-con e-child\" data-id=\"a3fb15f\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/clinicabenissa.com\/de\/zahnmedizin\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab64528 elementor-widget elementor-widget-image\" data-id=\"ab64528\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dr.-Ignacio-Calatayud-300x300.jpg\" class=\"attachment-medium size-medium wp-image-7836\" alt=\"Clinica Benissa - Dr. Ignacio Calatayud\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dr.-Ignacio-Calatayud-300x300.jpg 300w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dr.-Ignacio-Calatayud-150x150.jpg 150w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Dr.-Ignacio-Calatayud.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73d8225 elementor-widget elementor-widget-heading\" data-id=\"73d8225\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dr. Ignacio Calatayud<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a6fca2 elementor-widget elementor-widget-heading\" data-id=\"9a6fca2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Implantologie und Oralchirurgie<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-fe5e13f e-con-full col e-flex e-con e-child\" data-id=\"fe5e13f\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/clinicabenissa.com\/de\/psychologie\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65f3886 elementor-widget elementor-widget-image\" data-id=\"65f3886\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Rian-van-Rijsbergen-300x300.jpg\" class=\"attachment-medium size-medium wp-image-7780\" alt=\"Clinica Benissa - Rian van Rijsbergen\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Rian-van-Rijsbergen-300x300.jpg 300w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Rian-van-Rijsbergen-150x150.jpg 150w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Rian-van-Rijsbergen.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0bb29a elementor-widget elementor-widget-heading\" data-id=\"f0bb29a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Rian van Rijsbergen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b50a64 elementor-widget elementor-widget-heading\" data-id=\"0b50a64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Psychologe<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-488e93c e-con-full col e-flex e-con e-child\" data-id=\"488e93c\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/clinicabenissa.com\/de\/physiotherapie\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fe17dd elementor-widget elementor-widget-image\" data-id=\"7fe17dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Marte-Sofia-Venema-300x300.jpg\" class=\"attachment-medium size-medium wp-image-7796\" alt=\"Clinica Benissa - Marte Sofia Venema\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Marte-Sofia-Venema-300x300.jpg 300w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Marte-Sofia-Venema-150x150.jpg 150w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Marte-Sofia-Venema.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d265b7c elementor-widget elementor-widget-heading\" data-id=\"d265b7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mars Sofie Venema<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f15646 elementor-widget elementor-widget-heading\" data-id=\"9f15646\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Physiotherapie<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-81e1f8c e-con-full col e-flex e-con e-child\" data-id=\"81e1f8c\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/clinicabenissa.com\/de\/podologie\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-053d182 elementor-widget elementor-widget-image\" data-id=\"053d182\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"295\" height=\"300\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/phillip2-e1762951031938-295x300.jpg\" class=\"attachment-medium size-medium wp-image-8769\" alt=\"\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/phillip2-e1762951031938-295x300.jpg 295w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/phillip2-e1762951031938-1006x1024.jpg 1006w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/phillip2-e1762951031938-768x782.jpg 768w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/phillip2-e1762951031938-1509x1536.jpg 1509w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/phillip2-e1762951031938-12x12.jpg 12w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/11\/phillip2-e1762951031938.jpg 1920w\" sizes=\"(max-width: 295px) 100vw, 295px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-734029e elementor-widget elementor-widget-heading\" data-id=\"734029e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Philipp Mann<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-028d2ce elementor-widget elementor-widget-heading\" data-id=\"028d2ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Podologie<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<div class=\"elementor-element elementor-element-827ee1e e-con-full col e-flex e-con e-child\" data-id=\"827ee1e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a00727 elementor-widget elementor-widget-image\" data-id=\"2a00727\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Angela-300x300.jpg\" class=\"attachment-medium size-medium wp-image-7855\" alt=\"Clinica Benissa - Angela\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Angela-300x300.jpg 300w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Angela-150x150.jpg 150w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2025\/09\/Clinica-Benissa-Angela.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-576deff elementor-widget elementor-widget-heading\" data-id=\"576deff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Angela Wijthoef<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b47d7b9 elementor-widget elementor-widget-heading\" data-id=\"b47d7b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Hilfsmittel<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4cb29c3 e-con-full col e-flex e-con e-child\" data-id=\"4cb29c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-691ad38 elementor-widget elementor-widget-image\" data-id=\"691ad38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Clinica-Benissa-Lotte-300x300.jpg\" class=\"attachment-medium size-medium wp-image-8985\" alt=\"Benissa Klinik Lotte\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Clinica-Benissa-Lotte-300x300.jpg 300w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Clinica-Benissa-Lotte-150x150.jpg 150w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Clinica-Benissa-Lotte-12x12.jpg 12w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Clinica-Benissa-Lotte.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18d90e7 elementor-widget elementor-widget-heading\" data-id=\"18d90e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Lotte Duncker<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afec03b elementor-widget elementor-widget-heading\" data-id=\"afec03b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Hilfsmittel<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4bf3a55 espsup espinf e-flex e-con-boxed e-con e-parent\" data-id=\"4bf3a55\" data-element_type=\"container\" data-e-type=\"container\" id=\"testimonios\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c5f37c subtitulo elementor-widget elementor-widget-text-editor\" data-id=\"1c5f37c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>ECHTE ZEUGNISSE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-732c839 elementor-widget elementor-widget-heading\" data-id=\"732c839\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schlie\u00dfen Sie sich Tausenden von begeisterten Patienten an<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25d9f40 elementor-widget elementor-widget-shortcode\" data-id=\"25d9f40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><pre class=\"ti-widget\"><template id=\"trustindex-google-widget-html\"><div class=\"ti-widget  ti-goog ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-time-locale=\"hace %d %s|hoy|d\u00eda|d\u00edas|semana|semanas|mes|meses|a\u00f1o|a\u00f1os\" data-plugin-version=\"13.2.9\" data-layout-id=\"5\" data-layout-category=\"slider\" data-set-id=\"ligth-border\" data-pid=\"\" data-language=\"es\" data-close-locale=\"Cerca\" data-review-target-width=\"275\" data-css-version=\"2\" data-reply-by-locale=\"Respuesta del propietario\" data-only-rating-locale=\"Esta usuario solo dej\u00f3 una calificaci\u00f3n.\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer ti-footer-grid source-Google\"> <div class=\"ti-fade-container\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating ti-rating-large\"> EXCELENTE <\/strong> <\/div> <span class=\"ti-stars star-lg\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">A base de <strong>26 rese\u00f1as<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <trustindex-image class=\"ti-logo-fb\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" loading=\"lazy\" alt=\"Google\"><\/trustindex-image> <\/div> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Siguiente rese\u00f1a\" role=\"button\" tabindex=\"0\"><\/div> <div class=\"ti-prev\" aria-label=\"Rese\u00f1a anterior\" role=\"button\" tabindex=\"0\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" data-time=\"1744675200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjU80WVlwm6Uzg2V0StUOhhSWFbnaZu1CYyfYItRiaPkOi-AkIo=w40-h40-c-rp-mo-br100\" alt=\"Majken profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Majken <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->I want to give my very best recommendation to doctor Max Meertens. What a fantastic person and service.\n\nMy ex-husband got seriously sick and since the hospital didn\u00b4t answer when I called, and I knew it can be difficult to get an ambulance just by calling 112 - I was so lucky to find Dr. Meertens by google. I called him and explained my ex-husbands symptoms and he said - I will come within half an hour.\n\nI took a taxi myself and arrived 2 min. before the doctor. He examined my ex - and very quickly concluded he had to go to the hospital as soon as possible and the best and quickest way was if I drove him myself. I did so and arrived safe at the hospital and got quick help for my ex.\n\nWe are both SO thankful that the doctor came so quick and did his examination and conclusion. We dont like to think about what could had happen if my ex should have waited several hours.\n\nNot only that - the doctor asked for updates since he would like to know what the hospital found out. It was so nice to feel the doctors interest in my ex\u00b4 wellbeing.\n\nThank you so much dr. Meertens<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1724544000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXPNPliYxmv7JeSp1vVoBmZxuvV6m3yp0zQfYaL4G-_ZxPfr-55=w40-h40-c-rp-mo-ba2-br100\" alt=\"Emma Emmaa profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Emma Emmaa <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Tr\u00e8s bonne clinique qui m\u2019a prise sans rdv pour une grosse otite \u00e0 su me comprendre et me donner des m\u00e9dicaments pour me soigner je recommande tr\u00e8s fortement, le m\u00e9decin \u00e9tais tr\u00e8s gentil et souriant, l\u2019accueil \u00e9tais parfait.\nTr\u00e8s bonne clinique, chaleureux et familiale\nJe recommande\nUpdate : la prescription \u00e9tait tellement bonne quand 2 jours l\u2019otite \u00e9tais soign\u00e9e<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1696032000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIbn2WFKe31B5lBZkODRhfqtT9WsFZGy8qIeLCBN2WDypGEIQ=w40-h40-c-rp-mo-br100\" alt=\"Bas Meijer profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Bas Meijer <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Snelle hulp, vriendelijk en meedenkend!\nDank voor de hechting!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1694131200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLigTEYwgKRimtfEXYJv28AwAs0gc7UGYRwEGIbOv04W1UejA=w40-h40-c-rp-mo-br100\" alt=\"sue horey profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> sue horey <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Always professional but kind, interested and most importantly listens.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1690156800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKeeeAlZJjJe0NIdaewiEZ8VHICyrLR_JLAcXwKuLyosPXd=w40-h40-c-rp-mo-br100\" alt=\"Izabele B. profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Izabele B. <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->The staff at the clinic are extremely responsive and communicative. Dr Meertens was very attentive, kind and professional - overall I am very satisfied with my treatment at Cl\u00ednica Benissa<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1642550400\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIlu2YkTQ2Pdl23vW-tfGOegmTXRIshk5b1fvQjLdwgFGCkpA=w40-h40-c-rp-mo-br100\" alt=\"Valerie Setcavage profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Valerie Setcavage <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Profesional care and  advice with complete explanation of clients  medical  concerns . Staff are  efficient, polit\u00e9 and very accomodating. Excellent  service!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1622160000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWspBVbXZ0kyWxnhZL4vBKaOzGlzXk5bBI_RhFYjFqZtKF3wwVFEQ=w40-h40-c-rp-mo-ba3-br100\" alt=\"Natasha Petkoska profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Natasha Petkoska <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Dr Alexandra es muy agradable y una gran profesional al mismo tiempo. Me ayud\u00f3 mucho con mis brakets. la aprecio y la recomiendo 100% a todos. Me alegro de encontrar una doctora como ella con la que pueda contar.Gracias otra vez<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1593475200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWHL2mvndXXSMtkla6hw1Dc5c6E0vtLp_DNpl24c5q2-tDKlRvJ=w40-h40-c-rp-mo-ba4-br100\" alt=\"Jo Pugh profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jo Pugh <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Superb staff and the world's most gentle dentist!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1584057600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLiDCwOzWMYlRx_bjsFD8zkQw2iwoIrgmxoXWMUPhv6xhuwpP8=w40-h40-c-rp-mo-br100\" alt=\"Saskia van Boggelen profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Saskia van Boggelen <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Zonder haast, met alle aandacht en humor.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div>   <div class=\"ti-verified-by ti-verified-by-row\" data-style=\"1\"> <div class=\"ti-inner\"> Verificado por: Trustindex <span class=\"ti-info-icon\"><\/span> <div class=\"ti-disclaimer\">La insignia verificada de Trustindex es el s\u00edmbolo universal de confianza. Solo las mejores empresas pueden obtener la insignia verificada si tienen una puntuaci\u00f3n de revisi\u00f3n superior a 4.5, basada en las rese\u00f1as de clientes de los \u00faltimos 12 meses. <a href=\"https:\/\/www.trustindex.io\/?a=sys&amp;c=wp-verified-badge&amp;url=\/the-trustindex-verified-badge\/\" target=\"_blank\" rel=\"noopener\">Leer m\u00e1s<\/a><\/div> <\/div> <\/div>  <\/div> <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/trustindex-google-widget.css?1774064471\"><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74cdb2b e-con-full e-flex e-con e-parent\" data-id=\"74cdb2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2473da1 elementor-widget elementor-widget-shortcode\" data-id=\"2473da1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"113\" class=\"elementor elementor-113\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-bf4a417 espsup espinf elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"bf4a417\" data-element_type=\"container\" data-e-type=\"container\" id=\"datos-contacto\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ca6a39a e-grid e-con-full e-con e-child\" data-id=\"ca6a39a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4b92b9e e-con-full e-flex e-con e-child\" data-id=\"4b92b9e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b20e3a0 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b20e3a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7580b57 elementor-widget elementor-widget-heading\" data-id=\"7580b57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">E-Mail<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b30e50 dato elementor-widget elementor-widget-heading\" data-id=\"5b30e50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/<span                 data-original-string='qevtQbaklDryrCjv9duyhA==00aVEOMy5DCH\/2\/+dvbbxY34ZCCZt5VL6dg7Kji0bJiUJc='                class='apbct-email-encoder'                title='Dieser Kontakt wurde von Anti-Spam by CleanTalk verschl\u00fcsselt. Klicken Sie hier, um ihn zu entschl\u00fcsseln. Um die Entschl\u00fcsselung abzuschlie\u00dfen, stellen Sie sicher, dass JavaScript in Ihrem Browser aktiviert ist.'>re<span class=\"apbct-blur\">*******<\/span>@<span class=\"apbct-blur\">************<\/span>sa.com<\/span>\"><span \n                data-original-string='3BEuZ6ngFQmxdnLgSdIsGw==00aYtxuFLv5SkTtxablNkaEeIXCEczNJx\/0iKi885nT4CY='\n                class='apbct-email-encoder'\n                title='Dieser Kontakt wurde von Anti-Spam by CleanTalk verschl\u00fcsselt. Klicken Sie hier, um ihn zu entschl\u00fcsseln. Um die Entschl\u00fcsselung abzuschlie\u00dfen, stellen Sie sicher, dass JavaScript in Ihrem Browser aktiviert ist.'>zu<span class=\"apbct-blur\">*******<\/span>@<span class=\"apbct-blur\">************<\/span>sa.com<\/span><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb29c1d e-con-full e-flex e-con e-child\" data-id=\"bb29c1d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6bcdb1b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6bcdb1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8c62c7 elementor-widget elementor-widget-heading\" data-id=\"e8c62c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pflege von Patienten<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c4ae15 dato elementor-widget elementor-widget-heading\" data-id=\"2c4ae15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"tel:+34965733157\">+34 96 573 3157<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-192f0c5 elementor-widget elementor-widget-heading\" data-id=\"192f0c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Whatsapp-Empfang<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6474b98 dato elementor-widget elementor-widget-heading\" data-id=\"6474b98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"tel:+34744787071\">+34 744 78 70 71<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d7cd8a elementor-widget elementor-widget-heading\" data-id=\"5d7cd8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">24-Stunden-Notf\u00e4lle<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2564b5c dato elementor-widget elementor-widget-heading\" data-id=\"2564b5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"tel:+34639604269\">+34 639 60 42 69<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fa3d459 e-con-full e-flex e-con e-child\" data-id=\"fa3d459\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a548c67 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a548c67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78f2364 elementor-widget elementor-widget-heading\" data-id=\"78f2364\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Adresse<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1af3458 dato elementor-widget elementor-widget-heading\" data-id=\"1af3458\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Av. del Pa\u00eds Valenci\u00e0 19<br>03720 Benissa, Alicante <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7cf03fe e-con-full e-flex e-con e-child\" data-id=\"7cf03fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c3ac24 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8c3ac24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-clock\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm61.8-104.4l-84.9-61.7c-3.1-2.3-4.9-5.9-4.9-9.7V116c0-6.6 5.4-12 12-12h32c6.6 0 12 5.4 12 12v141.7l66.8 48.6c5.4 3.9 6.5 11.4 2.6 16.8L334.6 349c-3.9 5.3-11.4 6.5-16.8 2.6z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6926133 elementor-widget elementor-widget-heading\" data-id=\"6926133\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fahrplan<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c60c504 dato elementor-widget elementor-widget-heading\" data-id=\"c60c504\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Arbeitstage<br>Von 09:15 bis 13:00<br><br>Zahn\u00e4rzte<br>\nMontag und Donnerstag von 09:15 bis 20:00 Uhr<br>dienstags und freitags von 09:15 bis 14:00 Uhr<br>Freitag von 09:00 bis 17:00 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-251d803 espsup espinf e-flex e-con-boxed e-con e-parent\" data-id=\"251d803\" data-element_type=\"container\" data-e-type=\"container\" id=\"contenido-blog\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f72d7d elementor-widget elementor-widget-heading\" data-id=\"2f72d7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nachrichten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb3e4a8 elementor-posts--align-center elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"bb3e4a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-9008 post type-post status-publish format-standard has-post-thumbnail hentry category-posts\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/clinicabenissa.com\/de\/un-curso-fantastico-sobre-terapia-biofuncional-con-la-dra-claudia-fernandez-llamas\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/04\/terapia-biofuncional.jpg\" class=\"attachment-medium_large size-medium_large wp-image-9009\" alt=\"\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/04\/terapia-biofuncional.jpg 640w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/04\/terapia-biofuncional-300x300.jpg 300w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/04\/terapia-biofuncional-150x150.jpg 150w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/04\/terapia-biofuncional-12x12.jpg 12w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Nachrichten<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/clinicabenissa.com\/de\/un-curso-fantastico-sobre-terapia-biofuncional-con-la-dra-claudia-fernandez-llamas\/\">\n\t\t\t\tEin fantastischer Kurs \u00fcber biofunktionelle Therapie mit Dr. Claudia Fernandez Llamas!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Die biofunktionelle Therapie korrigiert nicht nur die Stellung der Z\u00e4hne, sondern wirkt auch auf die Ursache des Problems ein. Punkte<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8993 post type-post status-publish format-standard has-post-thumbnail hentry category-posts\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/clinicabenissa.com\/de\/zwischen-dem-9-und-23-marz-in-der-clinica-benissa-zu-konsultieren\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"942\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/02\/PHOTO-2026-02-26-15-52-07-768x942.jpg\" class=\"attachment-medium_large size-medium_large wp-image-8994\" alt=\"\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/02\/PHOTO-2026-02-26-15-52-07-768x942.jpg 768w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/02\/PHOTO-2026-02-26-15-52-07-245x300.jpg 245w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/02\/PHOTO-2026-02-26-15-52-07-835x1024.jpg 835w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/02\/PHOTO-2026-02-26-15-52-07-1253x1536.jpg 1253w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/02\/PHOTO-2026-02-26-15-52-07-10x12.jpg 10w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/02\/PHOTO-2026-02-26-15-52-07.jpg 1305w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Nachrichten<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/clinicabenissa.com\/de\/zwischen-dem-9-und-23-marz-in-der-clinica-benissa-zu-konsultieren\/\">\n\t\t\t\tDisponible para consultas en la Cl\u00ednica Benissa a partir del marzo\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Mit gro\u00dfer Freude stellen wir Ihnen Ward Waardenburg vor, einen in den Niederlanden ausgebildeten Facharzt f\u00fcr Familien- und Gemeinschaftsmedizin.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8950 post type-post status-publish format-standard has-post-thumbnail hentry category-posts\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/clinicabenissa.com\/de\/erweiterung-des-medizinischen-teams\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"552\" src=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Floor-Welling-e1772270408898-768x552.jpg\" class=\"attachment-medium_large size-medium_large wp-image-8954\" alt=\"\" srcset=\"https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Floor-Welling-e1772270408898-768x552.jpg 768w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Floor-Welling-e1772270408898-300x215.jpg 300w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Floor-Welling-e1772270408898-1024x735.jpg 1024w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Floor-Welling-e1772270408898-1536x1103.jpg 1536w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Floor-Welling-e1772270408898-18x12.jpg 18w, https:\/\/clinicabenissa.com\/wp-content\/uploads\/2026\/01\/Floor-Welling-e1772270408898.jpg 1607w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Nachrichten<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/clinicabenissa.com\/de\/erweiterung-des-medizinischen-teams\/\">\n\t\t\t\tWir erweitern das medizinische Team!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Einige von Ihnen kennen sie bereits von zwei Praktika in den letzten Jahren. Sie hat jetzt abgeschlossen<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e56290 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1e56290\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/clinicabenissa.com\/de\/nachrichten\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weitere Nachrichten<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Cuidamos de ti y de tu salud Cl\u00ednica Benissa ofrece atenci\u00f3n m\u00e9dica integral con un enfoque cercano y personalizado. Contamos [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-13","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/pages\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":0,"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"wp:attachment":[{"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}