{"id":2906,"date":"2020-02-29T10:44:43","date_gmt":"2020-02-29T09:44:43","guid":{"rendered":"https:\/\/clinicabenissa.com\/?p=2906"},"modified":"2025-10-01T15:42:55","modified_gmt":"2025-10-01T13:42:55","slug":"was-zu-tun-ist-wenn-sie-vermuten-dass-sie-das-coronavirus-haben","status":"publish","type":"post","link":"https:\/\/clinicabenissa.com\/de\/was-zu-tun-ist-wenn-sie-vermuten-dass-sie-das-coronavirus-haben\/","title":{"rendered":"Was ist zu tun, wenn Sie den Verdacht haben, dass Sie das Coronavirus haben?"},"content":{"rendered":"<p><b>HINWEIS im Zusammenhang mit der NEUEN CORONAVIRUS-Krankheit (COVID-19)\u00a0<\/b><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> Wenn Sie Symptome haben, die auf eine akute Atemwegsinfektion hindeuten, wie Fieber, Husten oder Kurzatmigkeit <\/span><b>y<\/b><span style=\"font-weight: 400;\"> wenn Sie von <a href=\"https:\/\/gisanddata.maps.arcgis.com\/apps\/opsdashboard\/index.html#\/bda7594740fd40299423467b48e9ecf6\" target=\"_blank\" rel=\"noopener noreferrer\">Risikobereiche<\/a> <\/span><span style=\"font-weight: 400;\">oder mit einem Patienten mit einer best\u00e4tigten COVID-19-Diagnose in Kontakt war, <\/span><b>muss zu Hause oder in einer Unterkunft bleiben<\/b><span style=\"font-weight: 400;\"> und wenden Sie sich telefonisch an 900300555, wo Sie \u00fcber die weiteren Schritte informiert werden.\u00a0<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> Wenn Sie sich in einem guten Gesundheitszustand befinden und wenn Sie aus <a href=\"https:\/\/gisanddata.maps.arcgis.com\/apps\/opsdashboard\/index.html#\/bda7594740fd40299423467b48e9ecf6\" target=\"_blank\" rel=\"noopener noreferrer\">Risikobereiche<\/a> <\/span><span style=\"font-weight: 400;\">\u00a0oder mit einem Patienten mit best\u00e4tigter COVID-19-Diagnose in Kontakt waren, k\u00f6nnen ihrem normalen Leben (Familie, Arbeit, Freizeit und\/oder Schule) nachgehen. \u00dcberwachen Sie Ihren Gesundheitszustand 14 Tage lang nach Ihrer Abreise aus den Risikogebieten oder dem Kontakt mit dem Patienten. Wenn er\/sie w\u00e4hrend dieser Zeit Symptome entwickelt, die mit einer akuten Atemwegsinfektion vereinbar sind, wie Fieber, Husten oder Kurzatmigkeit, <\/span><b>muss zu Hause oder in einer Unterkunft bleiben<\/b><span style=\"font-weight: 400;\"> und wenden Sie sich telefonisch an 900300555, wo Sie \u00fcber die weiteren Schritte informiert werden.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">(Quelle: <\/span><a href=\"https:\/\/www.mscbs.gob.es\/profesionales\/saludPublica\/ccayes\/alertasActual\/nCov-China\/ciudadania.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><i><span style=\"font-weight: 400;\">Ministerium f\u00fcr Gesundheit<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">)<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Wenn Sie Fragen haben, wenden Sie sich bitte an uns.<\/span><\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>AVISO relacionado con la enfermedad por NUEVO CORONAVIRUS (COVID-19)\u00a0 Si presenta una sintomatolog\u00eda compatible con una infecci\u00f3n respiratoria aguda, como [&hellip;]<\/p>","protected":false},"author":3,"featured_media":2908,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[40],"tags":[],"class_list":["post-2906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posts"],"_links":{"self":[{"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/posts\/2906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/comments?post=2906"}],"version-history":[{"count":0,"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/posts\/2906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/media\/2908"}],"wp:attachment":[{"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/media?parent=2906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/categories?post=2906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicabenissa.com\/de\/wp-json\/wp\/v2\/tags?post=2906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}