{"id":3617,"date":"2024-11-02T15:33:52","date_gmt":"2024-11-02T14:33:52","guid":{"rendered":"https:\/\/clinicabenissa.com\/?p=3617"},"modified":"2025-12-08T10:48:04","modified_gmt":"2025-12-08T09:48:04","slug":"vaccin-contre-la-grippe-saisonniere-2","status":"publish","type":"post","link":"https:\/\/clinicabenissa.com\/fr\/vaccin-contre-la-grippe-saisonniere-2\/","title":{"rendered":"Vaccin contre la grippe saisonni\u00e8re, pour ceux qui n'ont pas eu l'occasion de se faire vacciner, nous avons prolong\u00e9 la p\u00e9riode de vaccination cet automne !"},"content":{"rendered":"<p>Comme chaque ann\u00e9e, nous organisons la \"journ\u00e9e de vaccination contre la grippe\" selon les recommandations de l'Organisation mondiale de la sant\u00e9 (OMS). Une seule dose sera utilis\u00e9e pour la pr\u00e9vention.<\/p>\n<p>Le vaccin est recommand\u00e9 pour les personnes suivantes :<\/p>\n<ul>\n<li>Les personnes \u00e2g\u00e9es de plus de 60 ans.<\/li>\n<li>Personnes souffrant de maladies pulmonaires chroniques (telles que la bronchite chronique et l'emphys\u00e8me, l'asthme, la bronchectasie, la tuberculose pulmonaire et la fibrose) ; de maladies cardiaques chroniques (telles que l'insuffisance cardiaque, l'hypertension et l'insuffisance cardiaque valvulaire) ; d'insuffisance r\u00e9nale chronique ; patients sous traitement immunosuppresseur ; de diab\u00e8te sucr\u00e9 et d'autres troubles m\u00e9taboliques moins courants ; de furonculose.<\/li>\n<li>Les personnes expos\u00e9es \u00e0 un risque \u00e9lev\u00e9 d'infection en raison de leur profession ou de la situation \u00e9pid\u00e9miologique et les personnes ayant de nombreux contacts avec des personnes \u00e0 risque \u00e9lev\u00e9 (m\u00e9decins, infirmi\u00e8res, membres de la famille).<\/li>\n<\/ul>\n<p>Plus d'informations : pour l'instant, il n'y a pas d'informations de la part du Minist\u00e8re de la Sant\u00e9, mais nous esp\u00e9rons que dans les prochains jours nous aurons les informations n\u00e9cessaires. Pour diverses raisons, le prix de revient du vaccin a augment\u00e9. Veuillez contacter notre r\u00e9ception pour plus de d\u00e9tails. En raison de la pand\u00e9mie de Covid-19, il peut y avoir des probl\u00e8mes d'approvisionnement, les rendez-vous seront pris selon le principe du premier arriv\u00e9, premier servi.<\/p>\n<p>Une liste de patients susceptibles de b\u00e9n\u00e9ficier du vaccin est disponible \u00e0 notre r\u00e9ception. Ce message n'atteint pas tous les patients, si vous pensez que quelqu'un dans votre entourage pourrait b\u00e9n\u00e9ficier du vaccin, merci de le lui faire savoir.<\/p>\n<p>Appelez-nous \u00e0 955733157 ou contactez notre r\u00e9ception pour plus d'informations ou pour prendre rendez-vous : <a href=\"mailto:re*******@************sa.com\" data-original-string=\"hdXjSzydHL2aU7HZBtn4Iw==00aXxmloKMrGUyNJSAke0sQFyaydjtEiVGYbkvkdBTeEeU=\" title=\"This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.\" target=\"_blank\" rel=\"noopener\"><span \n                data-original-string='\/kjwpgSFOxaehfeGFAoLBg==00aVSnlNzzyvBJY8v3ZR2YYxAo7NxxGpPxOUlqFKBaqxRU='\n                class='apbct-email-encoder'\n                title='This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.'>re<span class=\"apbct-blur\">*******<\/span>@<span class=\"apbct-blur\">************<\/span>sa.com<\/span><\/a><\/p>\n<p><span style=\"color: #ff0000;\"><em>Ce vaccin est le vaccin contre l'influenza (grippe), nous ne sommes actuellement PAS en mesure d'administrer le vaccin Covid-19 dans notre clinique.\u00a0<\/em><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme chaque ann\u00e9e, nous organisons la \"journ\u00e9e de vaccination contre la grippe\". Une seule dose sera utilis\u00e9e pour la pr\u00e9vention.<\/p>","protected":false},"author":3,"featured_media":331,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[40],"tags":[],"class_list":["post-3617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posts"],"_links":{"self":[{"href":"https:\/\/clinicabenissa.com\/fr\/wp-json\/wp\/v2\/posts\/3617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicabenissa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicabenissa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicabenissa.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicabenissa.com\/fr\/wp-json\/wp\/v2\/comments?post=3617"}],"version-history":[{"count":0,"href":"https:\/\/clinicabenissa.com\/fr\/wp-json\/wp\/v2\/posts\/3617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicabenissa.com\/fr\/wp-json\/wp\/v2\/media\/331"}],"wp:attachment":[{"href":"https:\/\/clinicabenissa.com\/fr\/wp-json\/wp\/v2\/media?parent=3617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicabenissa.com\/fr\/wp-json\/wp\/v2\/categories?post=3617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicabenissa.com\/fr\/wp-json\/wp\/v2\/tags?post=3617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}